{"id":2630,"date":"2014-12-30T09:49:28","date_gmt":"2014-12-30T08:49:28","guid":{"rendered":"http:\/\/theatre-en-liberte.com\/blog\/?p=2630"},"modified":"2015-01-08T22:02:07","modified_gmt":"2015-01-08T21:02:07","slug":"le-colonel-oiseau-de-hristo-boytchov-par-le-theatre-en-liberte","status":"publish","type":"post","link":"https:\/\/theatre-en-liberte.com\/blog\/le-colonel-oiseau-de-hristo-boytchov-par-le-theatre-en-liberte\/","title":{"rendered":"Le Colonel Oiseau, de Hristo Boytchev, par le Th\u00e9\u00e2tre en libert\u00e9"},"content":{"rendered":"<p>Dans Vertou Magazine, le 30\u00a0d\u00e9cembre 2014&#8230;<\/p>\n<p><a href=\"http:\/\/theatre-en-liberte.com\/blog\/wp-content\/uploads\/2014-12-30-vertou-mag.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2629\" src=\"http:\/\/theatre-en-liberte.com\/blog\/wp-content\/uploads\/2014-12-30-vertou-mag-700x500.jpg\" alt=\"2014-12-30-vertou-mag\" width=\"660\" height=\"471\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans Vertou Magazine, le 30\u00a0d\u00e9cembre 2014&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[23,17],"tags":[],"class_list":["post-2630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-colonel-oiseau","category-presse"],"_links":{"self":[{"href":"https:\/\/theatre-en-liberte.com\/blog\/wp-json\/wp\/v2\/posts\/2630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theatre-en-liberte.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theatre-en-liberte.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theatre-en-liberte.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/theatre-en-liberte.com\/blog\/wp-json\/wp\/v2\/comments?post=2630"}],"version-history":[{"count":2,"href":"https:\/\/theatre-en-liberte.com\/blog\/wp-json\/wp\/v2\/posts\/2630\/revisions"}],"predecessor-version":[{"id":2634,"href":"https:\/\/theatre-en-liberte.com\/blog\/wp-json\/wp\/v2\/posts\/2630\/revisions\/2634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theatre-en-liberte.com\/blog\/wp-json\/wp\/v2\/media\/2629"}],"wp:attachment":[{"href":"https:\/\/theatre-en-liberte.com\/blog\/wp-json\/wp\/v2\/media?parent=2630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theatre-en-liberte.com\/blog\/wp-json\/wp\/v2\/categories?post=2630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theatre-en-liberte.com\/blog\/wp-json\/wp\/v2\/tags?post=2630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}